{"id":128,"date":"2023-06-15T19:38:46","date_gmt":"2023-06-15T19:38:46","guid":{"rendered":"https:\/\/poesiesommer.ch\/?page_id=128"},"modified":"2025-10-28T21:32:25","modified_gmt":"2025-10-28T21:32:25","slug":"november","status":"publish","type":"page","link":"https:\/\/poesiesommer.ch\/index.php\/november\/","title":{"rendered":"November"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"128\" class=\"elementor elementor-128\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e52e162 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e52e162\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6d48a7e\" data-id=\"6d48a7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b51b26c elementor-widget elementor-widget-ekit-nav-menu\" data-id=\"b51b26c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"ekit-nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<nav class=\"ekit-wid-con ekit_menu_responsive_tablet\"\n\t\t\tdata-hamburger-icon=\"\"\n\t\t\tdata-hamburger-icon-type=\"icon\"\n\t\t\tdata-responsive-breakpoint=\"1024\">\n\t\t\t            <button class=\"elementskit-menu-hamburger elementskit-menu-toggler\"  type=\"button\" aria-label=\"hamburger-icon\">\n                                    <span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span><span class=\"elementskit-menu-hamburger-icon\"><\/span>\n                            <\/button>\n            <div id=\"ekit-megamenu-hauptmenu\" class=\"elementskit-menu-container elementskit-menu-offcanvas-elements elementskit-navbar-nav-default ekit-nav-menu-one-page-no ekit-nav-dropdown-hover\"><ul id=\"menu-hauptmenu\" class=\"elementskit-navbar-nav elementskit-menu-po-right submenu-click-on-icon\"><li id=\"menu-item-91\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-has-children menu-item-91 nav-item elementskit-dropdown-has relative_position elementskit-dropdown-menu-default_width elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/\" class=\"ekit-menu-nav-link ekit-menu-dropdown-toggle\">Programm<i aria-hidden=\"true\" class=\"icon icon-down-arrow1 elementskit-submenu-indicator\"><\/i><\/a>\n<ul class=\"elementskit-dropdown elementskit-submenu-panel\">\n\t<li id=\"menu-item-473\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-473 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/juli\/\" class=\" dropdown-item\">Juli<\/a>\t<li id=\"menu-item-471\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-471 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/august\/\" class=\" dropdown-item\">August<\/a>\t<li id=\"menu-item-470\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-470 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/september\/\" class=\" dropdown-item\">September<\/a>\t<li id=\"menu-item-469\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-469 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/oktober\/\" class=\" dropdown-item\">Oktober<\/a>\t<li id=\"menu-item-468\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-468 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/november\/\" class=\" dropdown-item\">November<\/a><\/ul>\n<\/li>\n<li id=\"menu-item-472\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-472 nav-item elementskit-mobile-builder-content\" data-vertical-menu=750px><a href=\"https:\/\/poesiesommer.ch\/index.php\/kontakt\/\" class=\"ekit-menu-nav-link\">Kontakt<\/a><\/li>\n<\/ul><div class=\"elementskit-nav-identity-panel\"><button class=\"elementskit-menu-close elementskit-menu-toggler\" type=\"button\">X<\/button><\/div><\/div>\n\t\t\t<div class=\"elementskit-menu-overlay elementskit-menu-offcanvas-elements elementskit-menu-toggler ekit-nav-menu--overlay\"><\/div>        <\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2962db7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2962db7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81479ce\" data-id=\"81479ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b2ad85 elementor-widget elementor-widget-text-editor\" data-id=\"7b2ad85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Seetaler Poesiesommer 2025<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d95ad00 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d95ad00\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a73162\" data-id=\"3a73162\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef94acc elementor-widget elementor-widget-text-editor\" data-id=\"ef94acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>November<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c1763eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c1763eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abc1386\" data-id=\"abc1386\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0814e3f elementor-widget elementor-widget-text-editor\" data-id=\"0814e3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h5><strong>Montag, 3. November, Aarau, 15 Uhr<\/strong><\/h5><p>\u00abIm Nebel ist die Landschaft ein weisses Blatt du \/ wendest es langsam liest Vorab-\/drucke von Fussnoten\u2026\u00bb schrieb der Schriftsteller und Altphilologe Virgilo Masciadri in seiner Mansarde an der Zelglistrasse in Aarau. Seine Schreibstube inspiriert noch heute und bietet anderen Literaten Gelegenheit, ihre Texte vorzustellen. Der Autor <strong>Max Dohner<\/strong> (Baden) ergreift diese Carte blanche und pr\u00e4sentiert einen Essay zum Thema \u00abLiteratur als geistige Landschaft\u00bb. \u2013 <strong>Angela Weber-Hohlfeldt<\/strong> (Seon) reflektiert in ihren Texten und Fotografien die Natur und pl\u00e4diert f\u00fcr \u00abmehr Wildnis\u00bb. Im Gedicht Monokultur schreibt sie: \u00abWenn&#8217;s nur noch eine \/ Wahrheit gibt angeblich \/ Dann wird die Welt zum Grab\u00bb. 2016 publizierte die in der DDR aufgewachsene Autorin und Anglistin das Buch <em>Max Frisch \u2013 Alfred Andersch: eine widerspr\u00fcchliche Freundschaft.<\/em> \u2013 Ort der Lesung: Zelglistrasse 60.<br \/><br \/><\/p><h5><b>Freitag, 7. November, St. Urban, Kloster, 17 Uhr<\/b><\/h5><p>\u00abSembra eccessivo l&#8217;odore \/ di gelsomino in cui vo ringioto \/ da questa farfalla \/ bianchissima che v\u00f2lita \/ vantadosi di nulla \/ e in cima alla salita controvento \/ sbietta verso un giardino, \/ si posa su un corimbo \/ di melo, si fa fiore.\u00bb \u2013 \u00abEs scheint \u00fcbertrieben zu sein, \/ der Jasminduft, in den ich verschluckt \/ werde durch diesen milchweissen \/ Schmetterling in seinem Flattern, \/ in seinem Mit-nichts-sich-Br\u00fcsten, \/ und zuoberst auf der Anh\u00f6he schwenkt er \/ im Gegenwind hin zum Garten, \/ setzt sich auf eine Apfelbaum-\/ dolde, wird Bl\u00fcte.\u00bb Dieses sp\u00e4te Gedicht von <strong>Giorgio Orelli<\/strong> findet sich im eben erschienenen zwei-sprachigen Band <em>Am Rande des Lebens \u2013 L&#8217;orlo della vita<\/em>, f\u00fcr den <strong>Christoph Ferber<\/strong> (Ragusa) aus den letzten Gedichten des 2013 verstorbenen Tessiner Dichters eine Auswahl traf und sie \u00fcbersetzte. Ebenfalls 2025 sind aus dem Nachlass des 2014 verstorbenen Lyrikers <strong>Virgilio Masciadri<\/strong> Gedichte unter dem Titel <em>Ultimo Canto<\/em> erschienen, die <strong>Monica Oliari<\/strong> (Aarau) auf Italienisch \u00fcbersetzt hat \u2013 Texte von grosser Eindringlichkeit: \u00abAufbl\u00e4ttern die \/ Agenda zum n\u00e4chsten Jahr \/ Sommer- \/ monate ansehen von denen \/ keiner weiss ob sie je \/ wiederkommen \/ wo \/ bin ich dann wenn einer \/ diese Tage z\u00e4hlt? Meine \/ Pl\u00e4ne reichen nicht \/ weiter als bis zur n\u00e4chsten \/ D\u00e4mmerung und wo \/ ist die die Quelle aus der \/ uns die Zeit zufliesst zu den besten \/ Stunden so reichlich \/ unsere H\u00e4nde f\u00fcllt dass wir \/ nicht merken \/ wie sie \/ uns durch die Finger rinnt?\u00bb \u2013 \u00abSfogliare l&#8217;agenda \/ al prossimo anno \/ mesi \/ d&#8217;estaste sotto agli occhi \/ dei quali nessuno sa se mai \/ ritorneranno \/ dove \/ sar\u00f2 io allora quando uno \/ conter\u00e0 questi giorni? I miei \/ progetti non bastano \/ al prossimo \/ crepuscolo e dove \/ \u00e8 la fonte da cui \/ a noi affluisce il tempo nelle \/ ore cos\u00ec riccamente \/ riempie le nostre mani da \/ non accorgerci come \/ ci scivoli tra le dita?\u00bb <strong>Cornelia Masciadri<\/strong> und<strong> Monica Oliari<\/strong> stellen die beiden herausragenden Lyriksammlungen vor und weisen auch auf Eigenheiten der \u00dcbersetzung hin. \u2013 Treffpunkt: vor der Klosterkirche.<br \/><br \/><\/p><h5><b>Donnerstag, 20. November, Aarau, 15 Uhr<\/b><\/h5><p><em>L&#8217;eau et les r\u00eaves<\/em> lautet ein Kapitel im Band <em>Gesammelte Gedichte 2010-2023<\/em> der in Waldkirch lebenden Autorin <strong>Eva-Maria Berg<\/strong>. Ihre Gedichte handeln von R\u00e4umen und Zeiten, vom Menschen, den Elementen. Und sie laden dazu ein, der Welt vorurteilslos zu begegnen: \u00ababer das licht \/ spricht dagegen \/ nur schwarz \/ zu sehen \/ aber das licht \/ spricht auch \/ von gefahr \/ sich blenden \/ zu lassen \/ statt alle \/ nuancen \/ wahrzunehmen\u00bb. Ihre j\u00fcngste Publikation hat die Autorin der Stadt Marseille gewidmet, wo sie manchen Schreibaufenthalt verbracht hat. \u2013 Ort der Lesung: Zelglistrasse 60.<br \/><br \/><\/p><h5><strong>Freitag, 21. November, Hochdorf, 13 Uhr<\/strong><\/h5><p>\u00abConfine \/\/ Ci protegge dall&#8217;altro \/ a giorni alterni, \/ ci difende dall&#8217;oltre \/ informe.\u00bb \u2013 \u00abGrenze \/\/ Sie bewahrt uns vor Anderem, \/ einen Tag, einen nicht, besch\u00fctzt uns vor Jenseitigem, das unf\u00f6rmig ist\u00bb, schreibt <strong>Pietro Montorfani<\/strong> (Cassarate) in seinem Gedichtband <em>Der Schatten der Welt \u2013 L&#8217;ombra del mondo<\/em>. <strong>Christoph Ferber<\/strong> (Ragusa) hat die Gedichte des Tessiner Autors \u00fcbersetzt. Sie sind diesen Herbst im Caracol Verlag (Warth) erschienen. <strong>Cornelia Masciadri<\/strong> (Hunzenschwil) stellt an dieser Buchvernissage zusammen mit dem Autor ausgew\u00e4hlte Texte vor. \u2013 Unweit der Grenze zu \u00d6sterreich und Italien, n\u00e4mlich in Scuol, ist die romanische Autorin <strong>Romana Ganzoni<\/strong> (Celerina) geboren. Aus ihren Gedichten und lyrischen Kurztexten sprechen intensives Erleben und Beobachten. \u2013 Eine kulturelle Br\u00fccke ins Welschland und bis nach Marokko schlagen der welsche Lyriker <strong>Bruno Mercier<\/strong> (Lausanne) und die Malerin <strong>Annette Korolnik<\/strong> (Loco TI) mit literarischen und visuellen Beitr\u00e4gen. <strong>Hansruedi Zeder<\/strong> (Hochdorf) bereichert den multidisziplin\u00e4ren Nachmittag mit Clavichordkompositionen aus der Schweiz und Europa. \u2013 Adresse: c\/o Zeder Lehmann, Urswilstrasse 29. \u2013 Treffpunkt f\u00fcr Ortsunkundige: Bahnhof Hochdorf, 12.45 Uhr.<br \/><br \/><\/p><h5><b>Freitag, 21. November, Chardonne, 19 Uhr<\/b><\/h5><p>\u00ab Ni d\u00e9but ni fin de ce qui reste du jour \/ \u00e0 sept heures pass\u00e9es\u2026 \u00bb \u00abKein Anfang und kein Ende was vom Tag \/ geblieben ist: nach sieben Uhr\u2026\u00bb: Die \u00dcbersetzerin <strong>Corinne Verdan-Moser<\/strong> (Chardonne) pr\u00e4sentiert mit <strong>Cornelia Masciadri<\/strong>, der Schwester des Dichters <strong>Virgilio Masciadri<\/strong> (1963-2014) die dreisprachige Ausgabe <em>Ultimo canto<\/em> von dessen Gedichten aus dem Nachlass. \u2013 Ort: Magasin de mots, Rue du Village 12.<br \/><br \/><\/p><h5><strong>Samstag<\/strong><b>, 22. November, Hunzenschwil, 18 Uhr<\/b><\/h5><p>\u00ab\u2026 so k\u00f6nnt ich dir schreiben das Beste \/ was ich dazugelernt habe sei \/ gleichg\u00fcltig \/ zu sein so wie jetzt beim Warten auf die\/ses Boot das mich mitnimmt irgendwohin wo \/ mein Gesicht \/ nur noch eins ist wie alle und niemand mich mehr fragt was sonst noch \/ sein k\u00f6nnte\u2026 \u00bb: Zum Langgedicht <em>Ultimo Canto<\/em> von <strong>Virgilio Masciadri<\/strong> hat der italienische Komponist <strong>Stefano Ghisleri<\/strong> eine Sonate geschrieben, die er erstmals \u00f6ffentlich auff\u00fchrt (Vorpremiere). \u2013 Adresse: c\/o Strebel Masciadri, Bahnhofstrasse 15.<br \/><br \/><\/p><h5><b>Sonntag, 23. November, Aarau, 11 Uhr<\/b><\/h5><p><em>Ultimo Canto<\/em> \u2013 Urauff\u00fchrung. \u00ab\u2026 nell&#8217;attesa di un qualsiasi possibile \/ mesaggio \/ senza \/ contarci\u00bb, endet Virgilio Masciadris Langgedicht <em>Ultimo Canto<\/em> in der italienischen \u00dcbersetzung von <strong>Monica Oliari<\/strong> (Aarau). <strong>Corinne Verdan-Moser<\/strong> (Chardonne) hat es auf Franz\u00f6sisch \u00fcbersetzt. Zusammen mit dem deutschen Original, das <strong>Cornelia Masciadri<\/strong> (Hunzenschwil) vortr\u00e4gt, ist es an dieser Vernissage dreisprachig zu h\u00f6ren. Der Komponist und Pianist<strong> Stefano Ghisleri<\/strong> (Brescia) spielt dazu seine gross angelegte viers\u00e4tzige Sonate <em>Ultimo Canto<\/em> als Urauff\u00fchrung. \u2013 Hinweise auf das wissenschaftliche Werk des Dichters und Altphilologen Masciadri gibt der Historiker <strong>Beat N\u00e4f<\/strong> (Aarau) und zum Abschluss dieser Matin\u00e9e pr\u00e4sentieren <strong>Manuel Jegerlehner<\/strong> (Klavier) und <strong>Luisa Murmann<\/strong> (Gesang) eine weitere Komposition zu einem Gedicht des Aargauer Lyrikers. \u2013 Ort: Alte Kantonsschule, Aula, Bahnhofstrasse 91.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08ca8eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08ca8eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ca56ed\" data-id=\"1ca56ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-800aae7 elementor-widget elementor-widget-text-editor\" data-id=\"800aae7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>* * *<\/p><p><span style=\"font-family: 'Cambria',serif; mso-ascii-theme-font: minor-latin; mso-hansi-theme-font: minor-latin; mso-bidi-font-family: Helvetica; mso-ansi-language: DE-CH;\">\u00a0<\/span><\/p><p><span style=\"font-family: 'Cambria',serif; mso-ascii-theme-font: minor-latin; mso-hansi-theme-font: minor-latin; mso-bidi-font-family: Helvetica; mso-ansi-language: DE-CH;\">Reservationen \/ Anfragen sind erbeten an: ulrich.suter.kultur@bluewin.ch<\/span><\/p><p><span style=\"font-family: 'Cambria',serif; mso-ascii-theme-font: minor-latin; mso-hansi-theme-font: minor-latin; mso-bidi-font-family: Helvetica; mso-ansi-language: DE-CH;\">\u00a0<\/span><\/p><p>* * *<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3c3aba7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3c3aba7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a934fa8\" data-id=\"a934fa8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3032905 elementor-widget elementor-widget-html\" data-id=\"3032905\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">window.addEventListener('DOMContentLoaded', function() {\n\njQuery(document).ready(function() {\n    jQuery('#wph-back-button').on('click', function() {\n      window.history.go(-1);\n      return false;\n    });\n});\n\n});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8cde837 elementor-widget elementor-widget-html\" data-id=\"8cde837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">window.addEventListener('DOMContentLoaded', function() {\n\njQuery(document).ready(function() {\n    jQuery('#wph-back-button').on('click', function() {\n      window.history.go(-1);\n      return false;\n    });\n});\n\n});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8442f9e elementor-widget elementor-widget-html\" data-id=\"8442f9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">window.addEventListener('DOMContentLoaded', function() {\n\njQuery(document).ready(function() {\n    jQuery('#wph-back-button').on('click', function() {\n      window.history.go(-1);\n      return false;\n    });\n});\n\n});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6443de6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6443de6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d71eeaf\" data-id=\"d71eeaf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-294600a\" data-id=\"294600a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d381323\" data-id=\"d381323\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c293a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c293a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d45f55a\" data-id=\"d45f55a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf9da33 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"cf9da33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"283\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SWISSLOS-Kanton-Aargau-sw.jpg\" class=\"attachment-large size-large wp-image-138\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SWISSLOS-Kanton-Aargau-sw.jpg 920w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SWISSLOS-Kanton-Aargau-sw-300x106.jpg 300w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SWISSLOS-Kanton-Aargau-sw-768x272.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cd351c4\" data-id=\"cd351c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d96dfde elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d96dfde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"121\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/kff_region_seetal_logotype.jpg\" class=\"attachment-large size-large wp-image-139\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/kff_region_seetal_logotype.jpg 955w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/kff_region_seetal_logotype-300x46.jpg 300w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/kff_region_seetal_logotype-768x117.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5af1bd7\" data-id=\"5af1bd7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91e116f elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"91e116f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"333\" height=\"436\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/08\/logo-oertlistiftung.jpg\" class=\"attachment-large size-large wp-image-816\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/08\/logo-oertlistiftung.jpg 333w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/08\/logo-oertlistiftung-229x300.jpg 229w\" sizes=\"(max-width: 333px) 100vw, 333px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d508f5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d508f5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-266c0f0\" data-id=\"266c0f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b4a1ad elementor-widget elementor-widget-html\" data-id=\"0b4a1ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">window.addEventListener('DOMContentLoaded', function() {\n\njQuery(document).ready(function() {\n    jQuery('#wph-back-button').on('click', function() {\n      window.history.go(-1);\n      return false;\n    });\n});\n\n});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c290d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c290d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-9f1d7bc\" data-id=\"9f1d7bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc7dcbe elementor-widget elementor-widget-text-editor\" data-id=\"bc7dcbe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Kulturkommission<\/b> <b>Hochdorf<\/b><br \/><b>Vereinigung Pro Heidegg<br \/>Historische Vereinigung Seetal<br \/><\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3fff2fd\" data-id=\"3fff2fd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d2f7a5 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3d2f7a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"281\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/EGS_Schriftzug_2_schwarz-1024x360.jpg\" class=\"attachment-large size-large wp-image-651\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/EGS_Schriftzug_2_schwarz-1024x360.jpg 1024w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/EGS_Schriftzug_2_schwarz-300x105.jpg 300w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/EGS_Schriftzug_2_schwarz-768x270.jpg 768w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/EGS_Schriftzug_2_schwarz.jpg 1512w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-42318e8\" data-id=\"42318e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3706ea8 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"3706ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"182\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-1024x233.jpg\" class=\"attachment-large size-large wp-image-565\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-1024x233.jpg 1024w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-300x68.jpg 300w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-768x175.jpg 768w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-1536x349.jpg 1536w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/06\/SCHWEDISCHE-BOTSCHAFT_BERN_RGB-2048x466.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad5de15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad5de15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-365b1e2\" data-id=\"365b1e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cd7846 elementor-widget elementor-widget-html\" data-id=\"1cd7846\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\">window.addEventListener('DOMContentLoaded', function() {\n\njQuery(document).ready(function() {\n    jQuery('#wph-back-button').on('click', function() {\n      window.history.go(-1);\n      return false;\n    });\n});\n\n});<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e36475 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e36475\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a72cd14\" data-id=\"a72cd14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d5bc16 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"9d5bc16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"296\" src=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-1024x379.png\" class=\"attachment-large size-large wp-image-965\" alt=\"\" srcset=\"https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-1024x379.png 1024w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-300x111.png 300w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-768x284.png 768w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-1536x569.png 1536w, https:\/\/poesiesommer.ch\/wp-content\/uploads\/2023\/11\/PRH_CD_RGB_black_DE_LOGO-2048x758.png 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4f8ffc4\" data-id=\"4f8ffc4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5b0bc81\" data-id=\"5b0bc81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Programm Juli August September Oktober November Kontakt X Seetaler Poesiesommer 2025 November Montag, 3. November, Aarau, 15 Uhr \u00abIm Nebel ist die Landschaft ein weisses Blatt du \/ wendest es langsam liest Vorab-\/drucke von Fussnoten\u2026\u00bb schrieb der Schriftsteller und Altphilologe Virgilo Masciadri in seiner Mansarde an der Zelglistrasse in Aarau. Seine Schreibstube inspiriert noch heute [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-128","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/pages\/128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":170,"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/pages\/128\/revisions"}],"predecessor-version":[{"id":1616,"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/pages\/128\/revisions\/1616"}],"wp:attachment":[{"href":"https:\/\/poesiesommer.ch\/index.php\/wp-json\/wp\/v2\/media?parent=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}